{"id":6,"count":2,"description":"Les comp\u00e9tences pro et perso de vos collaborateurs sont des atouts pr\u00e9cieux pour votre entreprise.\r\n\r\nLongtemps ignor\u00e9es par les recruteurs, les comp\u00e9tences personnelles sont au centre des pr\u00e9occupations actuelles de l\u2019entreprise. Elles sont les garantes d\u2019une ambiance de travail r\u00e9ussie ! C\u2019est pourquoi il est important de les envisager d\u00e8s le recrutement. La r\u00e9flexion sur les comp\u00e9tences personnelles s\u2019inscrit dans une prise de conscience plus large autour des valeurs de l\u2019entreprise. Notamment le d\u00e9veloppement du concept de marque employeur. Ces derni\u00e8res ann\u00e9es, on voit appara\u00eetre un questionnement plus vaste sur la place de chacun dans cette d\u00e9marche de qualit\u00e9. Nous vous donnons des astuces pour vous aider \u00e0 les d\u00e9celer en entretien, ou chez un nouvel arrivant, mais aussi aider vos collaborateurs \u00e0 les affirmer dans leur vie professionnelle. Les comp\u00e9tences personnelles, en tant que savoir-\u00eatre transverses, font le lien entre les valeurs de l\u2019entreprise et celles des individus.\r\nDepuis quelques ann\u00e9es la formation professionnelle a aussi le vent en poupe, et \u00e0 raison ! Quelle que soit leur taille, les entreprises sont de plus en plus nombreuses \u00e0 accompagner leurs salari\u00e9s vers la formation. Vous vous demandez peut-\u00eatre quelles sont les raisons de ce succ\u00e8s ?\u00a0Elles sont nombreuses car la formation professionnelle n\u2019est pas d\u00e9pourvue d\u2019avantages pour les salari\u00e9s comme pour les entreprises. Elle permet de valoriser votre marque employeur et d\u2019augmenter la motivation de vos salari\u00e9s en m\u00eame temps. Et ce n\u2019est pas tout, on vous en dit plus sur ses nombreux atouts ! \u00a0\r\n<!-- \/wp:paragraph -->\r\n\r\nAu-del\u00e0 du recrutement, vous souhaitez permettre\u00a0 \u00e0 vos collaborateurs d'entretenir ces comp\u00e9tences pro et perso pour mieux se r\u00e9v\u00e9ler ? Nos experts vous proposent quelques pistes\u2026\r\n\r\n&nbsp;","link":"https:\/\/pro.myfairjob.com\/articles\/conseils-rh\/competences-professionnelles-et-personnelles\/","name":"Comp\u00e9tences pro et perso","slug":"competences-professionnelles-et-personnelles","taxonomy":"category","parent":4,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comp\u00e9tences pro et perso | Les conseils myfairJob<\/title>\n<meta name=\"description\" content=\"Les comp\u00e9tences pro et perso de vos collaborateurs sont des atouts pr\u00e9cieux pour votre entreprise. Au-del\u00e0 du recrutement, aidez-les \u00e0 mieux se r\u00e9v\u00e9ler !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pro.myfairjob.com\/articles\/conseils-rh\/competences-professionnelles-et-personnelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comp\u00e9tences pro et perso | Les conseils myfairJob\" \/>\n<meta property=\"og:description\" content=\"Les comp\u00e9tences pro et perso de vos collaborateurs sont des atouts pr\u00e9cieux pour votre entreprise. Au-del\u00e0 du recrutement, aidez-les \u00e0 mieux se r\u00e9v\u00e9ler !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pro.myfairjob.com\/articles\/conseils-rh\/competences-professionnelles-et-personnelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog myfairJob Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pro.myfairjob.com\/articles\/#website\",\"url\":\"https:\/\/pro.myfairjob.com\/articles\/\",\"name\":\"Blog myfairJob Pro\",\"description\":\"Blog myfairJob Pro\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/pro.myfairjob.com\/articles\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/pro.myfairjob.com\/articles\/conseils-rh\/competences-professionnelles-et-personnelles\/#webpage\",\"url\":\"https:\/\/pro.myfairjob.com\/articles\/conseils-rh\/competences-professionnelles-et-personnelles\/\",\"name\":\"Comp\\u00e9tences pro et perso | Les conseils myfairJob\",\"isPartOf\":{\"@id\":\"https:\/\/pro.myfairjob.com\/articles\/#website\"},\"description\":\"Les comp\\u00e9tences pro et perso de vos collaborateurs sont des atouts pr\\u00e9cieux pour votre entreprise. Au-del\\u00e0 du recrutement, aidez-les \\u00e0 mieux se r\\u00e9v\\u00e9ler !\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pro.myfairjob.com\/articles\/conseils-rh\/competences-professionnelles-et-personnelles\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/pro.myfairjob.com\/articles\/wp-json\/wp\/v2\/categories\/6"}],"collection":[{"href":"https:\/\/pro.myfairjob.com\/articles\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/pro.myfairjob.com\/articles\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/pro.myfairjob.com\/articles\/wp-json\/wp\/v2\/categories\/4"}],"wp:post_type":[{"href":"https:\/\/pro.myfairjob.com\/articles\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}